{"id":8192,"date":"2025-06-05T09:24:31","date_gmt":"2025-06-05T02:24:31","guid":{"rendered":"https:\/\/www.cmc.co.th\/wetalk\/?p=8192"},"modified":"2025-06-05T10:05:14","modified_gmt":"2025-06-05T03:05:14","slug":"%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3","status":"publish","type":"post","link":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/","title":{"rendered":"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8192\" class=\"elementor elementor-8192\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ab542c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ab542c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e791b24\" data-id=\"e791b24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7501861 elementor-widget elementor-widget-heading\" data-id=\"7501861\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\" style=\"outline-style: initial; outline-width: 0px;\"><\/h2><h2 data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\" style=\"outline-style: initial; outline-width: 0px;\">\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07<span style=\"color: rgb(16, 16, 16); font-family: &quot;Bai Jamjuree&quot;, sans-serif; font-size: 1.75rem; font-weight: 700;\"><\/span><\/h2><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f71bb8 elementor-widget elementor-widget-image\" data-id=\"2f71bb8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e077.webp\" class=\"attachment-full size-full wp-image-8162\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e077.webp 1920w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e077-300x169.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e077-1024x576.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e077-768x432.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e077-1536x864.webp 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6b0a98 elementor-widget elementor-widget-text-editor\" data-id=\"d6b0a98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e22\u0e48\u0e32\u0e19 \u201c\u0e40\u0e01\u0e29\u0e15\u0e23\u201d \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e04\u0e48\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e01\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e35\u0e48\u0e43\u0e04\u0e23\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e04\u0e38\u0e49\u0e19\u0e2b\u0e39 \u0e41\u0e15\u0e48\u0e04\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e25\u0e07\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e43\u0e19\u0e22\u0e48\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 5-10 \u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e21\u0e32 \u201c\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u201d \u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 <strong>\u201c\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32 \u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u201d<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7a1872 elementor-widget elementor-widget-image\" data-id=\"d7a1872\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1344\" height=\"768\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e071.webp\" class=\"attachment-full size-full wp-image-8156\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e071.webp 1344w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e071-300x171.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e071-1024x585.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e071-768x439.webp 768w\" sizes=\"(max-width: 1344px) 100vw, 1344px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-055f277 elementor-widget elementor-widget-text-editor\" data-id=\"055f277\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"padding-bottom: 5px;\"><strong>1.\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 &#8211; \u0e04\u0e23\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e01<\/strong><\/div>\n<div>\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e04\u0e37\u0e2d \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1d\u0e31\u0e48\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19<\/div>\n<div style=\"padding-left: 40px; padding-top: 10px;\">\n\n\u2022 \u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e32\u0e22\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27 (BTS \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c) : \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e19\u0e32\u0e17\u0e35\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e42\u0e15\u0e27\u0e4c \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e04\u0e21\u0e1b\u0e31\u0e2a \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e23\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e43\u0e08\u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c \u0e2a\u0e22\u0e32\u0e21 \u0e2d\u0e42\u0e28\u0e01 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01\n<div>\u2022 \u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e32\u0e22\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 (\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15) : \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e27\u0e34\u0e48\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e22\u0e01\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e43\u0e19\u0e22\u0e48\u0e32\u0e19\u0e19\u0e35\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/div>\n<div>\u2022 \u0e17\u0e32\u0e07\u0e14\u0e48\u0e27\u0e19\/\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c : \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e2a\u0e39\u0e48\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e2d\u0e32\u0e08\u0e13\u0e23\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e28\u0e23\u0e35\u0e23\u0e31\u0e0a \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e2d\u0e01\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29786cf elementor-widget elementor-widget-image\" data-id=\"29786cf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1392\" height=\"752\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e072.webp\" class=\"attachment-full size-full wp-image-8157\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e072.webp 1392w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e072-300x162.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e072-1024x553.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e072-768x415.webp 768w\" sizes=\"(max-width: 1392px) 100vw, 1392px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5bcbcd elementor-widget elementor-widget-text-editor\" data-id=\"c5bcbcd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"padding-bottom: 5px;\"><strong>2.\u0e23\u0e32\u0e22\u0e25\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33 : \u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e40\u0e0a\u0e48\u0e32\u0e01\u0e47\u0e07\u0e48\u0e32\u0e22 \u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e2a\u0e1a\u0e32\u0e22<\/strong><\/div>\n<div>\u0e22\u0e48\u0e32\u0e19\u0e19\u0e35\u0e49\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e23\u0e27\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u201d \u0e0a\u0e31\u0e49\u0e19\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e14\u0e35\u0e21\u0e32\u0e19\u0e14\u0e4c\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e32\u0e22\u0e25\u0e49\u0e2d\u0e21 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e43\u0e19\u0e22\u0e48\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e40\u0e0a\u0e48\u0e32\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 Yield \u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e1e\u0e2d\u0e43\u0e08 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27<\/div>\n<div style=\"padding-left: 40px; padding-top: 10px;\">\n\n\u2022 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c (\u0e1a\u0e32\u0e07\u0e40\u0e02\u0e19) : \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e15\u0e49\u0e19 \u0e46 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e21\u0e35\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e23\u0e27\u0e21\u0e15\u0e31\u0e27\u0e01\u0e31\u0e19\u0e19\u0e31\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e23\u0e32\u0e22\n<div>\u2022 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 : \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e42\u0e15\u0e27\u0e4c \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e04\u0e21\u0e1b\u0e31\u0e2a \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e19\u0e32\u0e17\u0e35<\/div>\n<div>\u2022 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e32\u0e18\u0e34\u0e15 \u0e21.\u0e40\u0e01\u0e29\u0e15\u0e23 (\u0e1b\u0e23\u0e30\u0e16\u0e21-\u0e21\u0e31\u0e18\u0e22\u0e21) : \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59ff29f elementor-widget elementor-widget-image\" data-id=\"59ff29f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1392\" height=\"752\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e073.webp\" class=\"attachment-full size-full wp-image-8158\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e073.webp 1392w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e073-300x162.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e073-1024x553.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e073-768x415.webp 768w\" sizes=\"(max-width: 1392px) 100vw, 1392px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb5bdd8 elementor-widget elementor-widget-text-editor\" data-id=\"eb5bdd8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"padding-bottom: 5px;\"><strong>3. \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e23\u0e23\u0e1e \u2013 \u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e21\u0e35\u0e2a\u0e35\u0e2a\u0e31\u0e19 \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/div><div>\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e0a\u0e2d\u0e1a\u0e0a\u0e2d\u0e1b \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e31\u0e48\u0e07\u0e0a\u0e34\u0e25\u0e17\u0e35\u0e48\u0e04\u0e32\u0e40\u0e1f\u0e48\u0e2a\u0e27\u0e22 \u0e46 \u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e21\u0e35\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e08\u0e1a\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e1a\u0e1a Active Living<\/div><div style=\"padding-left: 40px; padding-top: 10px;\"><p>\u2022 \u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 (\u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e25\u0e01\u0e0a\u0e34\u0e1b\u0e02\u0e2d\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25) \u0e22\u0e48\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e41\u0e25\u0e30\u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e<\/p><div>\u2022 \u0e40\u0e21\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e23\u0e31\u0e0a\u0e42\u0e22\u0e18\u0e34\u0e19: \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e04\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e42\u0e23\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 Co-working space<\/div><div>\u2022 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e04\u0e32\u0e40\u0e1f\u0e48\u0e40\u0e01\u0e4b\u0e46 : \u0e23\u0e2d\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e32\u0e40\u0e1f\u0e48\u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e14\u0e35 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e41\u0e01\u0e48\u0e01\u0e32\u0e23\u0e19\u0e31\u0e48\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afef849 elementor-widget elementor-widget-image\" data-id=\"afef849\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1392\" height=\"752\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e074.webp\" class=\"attachment-full size-full wp-image-8159\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e074.webp 1392w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e074-300x162.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e074-1024x553.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e074-768x415.webp 768w\" sizes=\"(max-width: 1392px) 100vw, 1392px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f2bc27 elementor-widget elementor-widget-text-editor\" data-id=\"7f2bc27\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"padding-bottom: 5px;\"><strong>4. \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33 \u2013 \u0e2d\u0e38\u0e48\u0e19\u0e43\u0e08\u0e17\u0e38\u0e01\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25<\/strong><\/div>\n<div>\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e48\u0e19\u0e43\u0e08\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e04\u0e37\u0e2d \u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e47\u0e23\u0e32\u0e22\u0e25\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e07\u0e27\u0e25 \u0e2b\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19&lt;\u0e1ddiv&gt;\n<div style=\"padding-left: 40px; padding-top: 10px;\">\n\n\u2022 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e1b\u0e32\u0e42\u0e25 \u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e17\u0e38\u0e01\u0e41\u0e1c\u0e19\u0e01 \u0e2d\u0e22\u0e39\u0e48\u0e43\u0e01\u0e25\u0e49 BTS \u0e40\u0e2a\u0e19\u0e32\u0e19\u0e34\u0e04\u0e21\n<div>\u2022 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35 : \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e21\u0e48\u0e44\u0e01\u0e25\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07<\/div>\n<div>\u2022 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\/\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 : \u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e2d\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0756f3 elementor-widget elementor-widget-image\" data-id=\"c0756f3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"889\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/002_Kaset-Campus_SIDE_FINAL.webp\" class=\"attachment-full size-full wp-image-8241\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/002_Kaset-Campus_SIDE_FINAL.webp 1600w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/002_Kaset-Campus_SIDE_FINAL-300x167.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/002_Kaset-Campus_SIDE_FINAL-1024x569.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/002_Kaset-Campus_SIDE_FINAL-768x427.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/002_Kaset-Campus_SIDE_FINAL-1536x853.webp 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e16793 elementor-widget elementor-widget-text-editor\" data-id=\"5e16793\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>\u201c\u0e0a\u0e32\u0e42\u0e15\u0e27\u0e4c \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e04\u0e21\u0e1b\u0e31\u0e2a\u201d<\/strong> <em><strong>\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e15\u0e48\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15<\/strong><\/em> \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e08\u0e01\u0e25\u0e32\u0e07\u0e17\u0e33\u0e40\u0e25\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e21\u0e35\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e02\u0e22\u0e31\u0e1a\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e40\u0e0a\u0e48\u0e32 \u0e01\u0e47\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64f41f3 elementor-widget elementor-widget-text-editor\" data-id=\"64f41f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 \u201c\u0e04\u0e23\u0e1a \u0e08\u0e1a \u0e04\u0e38\u0e49\u0e21\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 <strong>\u201c\u0e0a\u0e32\u0e42\u0e15\u0e27\u0e4c \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e04\u0e21\u0e1b\u0e31\u0e2a\u201d<\/strong> \u0e04\u0e37\u0e2d\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e21\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e21 \u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e42\u0e17\u0e23 1172 \u0e01\u0e14 3 \u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e34\u0e40\u0e28\u0e29 ! \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a href=\"https:\/\/www.cmc.co.th\/chateau-kaset\/\">https:\/\/www.cmc.co.th\/chateau-kaset\/<\/a> (*\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f\u0e01\u0e33\u0e2b\u0e19\u0e14)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-75d62e0\" data-id=\"75d62e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a6f47b elementor-widget elementor-widget-text-editor\" data-id=\"4a6f47b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4397\" class=\"elementor elementor-4397\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e561d41 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e561d41\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e730739\" data-id=\"e730739\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efe2678 elementor-widget elementor-widget-heading\" data-id=\"efe2678\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CMC We Talk<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4f5593 elementor-widget elementor-widget-text-editor\" data-id=\"d4f5593\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d94be4f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d94be4f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b246e2 elementor-widget elementor-widget-text-editor\" data-id=\"7b246e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLatest Content \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0068340 elementor-grid-eael-col-1 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"0068340\" data-element_type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-1&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"eael-post-grid-0068340\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-0068340 eael-post-grid-style-two\" data-layout-mode=\"grid\"><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"8647\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/www.cmc.co.th\/wetalk\/cmc-%e0%b8%88%e0%b8%b1%e0%b8%9a%e0%b8%a1%e0%b8%b7%e0%b8%ad-%e0%b8%a1-%e0%b8%a8%e0%b8%a3%e0%b8%b5%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1-%e0%b8%94%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a1%e0%b9%80%e0%b8%94\/\"><\/a><\/div><div class=\"eael-entry-thumbnail \">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d-1024x1024.webp\" class=\"attachment-large size-large wp-image-8653\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d.webp 1244w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n                              <\/div>\n                      <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/www.cmc.co.th\/wetalk\/cmc-%e0%b8%88%e0%b8%b1%e0%b8%9a%e0%b8%a1%e0%b8%b7%e0%b8%ad-%e0%b8%a1-%e0%b8%a8%e0%b8%a3%e0%b8%b5%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1-%e0%b8%94%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a1%e0%b9%80%e0%b8%94\/\" title=\"CMC \u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e21.\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e14\u0e31\u0e19\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e2f\u200b \u200b\u200b\u0e40\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e32\u0e21\u0e08\u0e23\u0e34\u0e07 \u201cCMC Student Affiliate\u201d \u0e1b\u0e31\u0e49\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u200b\">CMC \u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e21.\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e14\u0e31\u0e19\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e2f\u200b \u200b\u200b\u0e40\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e32\u0e21\u0e08\u0e23\u0e34\u0e07 \u201cCMC Student Affiliate\u201d \u0e1b\u0e31\u0e49\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u200b<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                    <div class=\"eael-grid-post-excerpt\"><a\n                                        href=\"https:\/\/www.cmc.co.th\/wetalk\/cmc-%e0%b8%88%e0%b8%b1%e0%b8%9a%e0%b8%a1%e0%b8%b7%e0%b8%ad-%e0%b8%a1-%e0%b8%a8%e0%b8%a3%e0%b8%b5%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1-%e0%b8%94%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a1%e0%b9%80%e0%b8%94\/\"\n                                        class=\"eael-post-elements-readmore-btn\">Read More<\/a><\/div>\n                                <\/div><div class=\"eael-entry-header-after style-two\"><div class=\"eael-entry-meta\"><span class=\"eael-meta-posted-on\"><i class=\"far fa-clock\"><\/i><time datetime=\"12 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2026\">12 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"8601\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/www.cmc.co.th\/wetalk\/10-%e0%b8%ad%e0%b8%b1%e0%b8%99%e0%b8%94%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%b1%e0%b8%95%e0%b8%a7%e0%b9%8c%e0%b9%80%e0%b8%a5%e0%b8%b5%e0%b9%89%e0%b8%a2%e0%b8%87%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%99\/\"><\/a><\/div><div class=\"eael-entry-thumbnail \">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012-1024x1024.jpg\" class=\"attachment-large size-large wp-image-8598\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012-1024x1024.jpg 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012-300x300.jpg 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012-150x150.jpg 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012-768x768.jpg 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n                              <\/div>\n                      <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/www.cmc.co.th\/wetalk\/10-%e0%b8%ad%e0%b8%b1%e0%b8%99%e0%b8%94%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%b1%e0%b8%95%e0%b8%a7%e0%b9%8c%e0%b9%80%e0%b8%a5%e0%b8%b5%e0%b9%89%e0%b8%a2%e0%b8%87%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%99\/\" title=\"10 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e22\u0e2d\u0e14\u0e19\u0e34\u0e22\u0e21\u0e43\u0e19\u0e44\u0e17\u0e22 \u0e1b\u0e35 2025 \u2013 \u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e04\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e39\u0e49!\">10 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e22\u0e2d\u0e14\u0e19\u0e34\u0e22\u0e21\u0e43\u0e19\u0e44\u0e17\u0e22 \u0e1b\u0e35 2025 \u2013 \u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e04\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e39\u0e49!<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                    <div class=\"eael-grid-post-excerpt\"><a\n                                        href=\"https:\/\/www.cmc.co.th\/wetalk\/10-%e0%b8%ad%e0%b8%b1%e0%b8%99%e0%b8%94%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%b1%e0%b8%95%e0%b8%a7%e0%b9%8c%e0%b9%80%e0%b8%a5%e0%b8%b5%e0%b9%89%e0%b8%a2%e0%b8%87%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%99\/\"\n                                        class=\"eael-post-elements-readmore-btn\">Read More<\/a><\/div>\n                                <\/div><div class=\"eael-entry-header-after style-two\"><div class=\"eael-entry-meta\"><span class=\"eael-meta-posted-on\"><i class=\"far fa-clock\"><\/i><time datetime=\"21 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2025\">21 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2025<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>            <div class=\"eael-load-more-button-wrap\">\n                <button class=\"eael-load-more-button\" id=\"eael-load-more-btn-0068340\" data-widget-id=\"0068340\" data-widget=\"0068340\" data-page-id=\"4397\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;default.php&quot;,&quot;name&quot;:&quot;Post-Grid&quot;}\" data-class=\"Essential_Addons_Elementor\\Elements\\Post_Grid\" data-layout=\"grid\" data-page=\"1\" data-args=\"orderby=date&amp;order=desc&amp;ignore_sticky_posts=1&amp;post_status=publish&amp;posts_per_page=2&amp;offset=0&amp;post_type=post&amp;tax_query%5B0%5D%5Btaxonomy%5D=category&amp;tax_query%5B0%5D%5Bfield%5D=term_id&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=21&amp;tax_query%5B0%5D%5Bterms%5D%5B1%5D=25&amp;tax_query%5Brelation%5D=AND\" data-max-page=\"164\">\n                    <span class=\"eael-btn-loader button__loader\"><\/span>\n                    <span class=\"eael_load_more_text\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\n                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e21\u0e32 \u201c\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u201d \u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 \u201c\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32 \u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u201d<\/p>\n","protected":false},"author":1,"featured_media":8160,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_canvas","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-8192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-around","odd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14<\/title>\n<meta name=\"description\" content=\"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e21\u0e32 \u201c\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u201d \u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 \u201c\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32 \u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmc.co.th\/wetalk\/\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e21\u0e32 \u201c\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u201d \u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 \u201c\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32 \u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmc.co.th\/wetalk\/\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\/\" \/>\n<meta property=\"og:site_name\" content=\"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-05T02:24:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T03:05:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\" \/>\n<meta name=\"twitter:description\" content=\"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e21\u0e32 \u201c\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u201d \u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 \u201c\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32 \u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u201d\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/00e11c9a5b4eeb918aad42ec1d6adfc7\"},\"headline\":\"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07\",\"datePublished\":\"2025-06-05T02:24:31+00:00\",\"dateModified\":\"2025-06-05T03:05:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/\"},\"wordCount\":25,\"publisher\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp\",\"articleSection\":[\"All Around\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/\",\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/\",\"name\":\"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\",\"isPartOf\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp\",\"datePublished\":\"2025-06-05T02:24:31+00:00\",\"dateModified\":\"2025-06-05T03:05:14+00:00\",\"description\":\"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e21\u0e32 \u201c\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u201d \u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 \u201c\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32 \u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u201d\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#primaryimage\",\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp\",\"contentUrl\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp\",\"width\":1920,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cmc.co.th\/wetalk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#website\",\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/\",\"name\":\"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\",\"description\":\"CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\",\"publisher\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cmc.co.th\/wetalk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#organization\",\"name\":\"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\",\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2021\/01\/cropped-t.jpg\",\"contentUrl\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2021\/01\/cropped-t.jpg\",\"width\":150,\"height\":150,\"caption\":\"CMC WE TALK |  CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\"},\"image\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/00e11c9a5b4eeb918aad42ec1d6adfc7\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b95b7349d23f2efc89b243b406187035f772e87867edf3bb4398abc87dcc097?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b95b7349d23f2efc89b243b406187035f772e87867edf3bb4398abc87dcc097?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/www.cmc.co.th\/wetalk\"],\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","description":"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e21\u0e32 \u201c\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u201d \u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 \u201c\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32 \u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmc.co.th\/wetalk\/\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","og_description":"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e21\u0e32 \u201c\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u201d \u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 \u201c\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32 \u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u201d","og_url":"https:\/\/www.cmc.co.th\/wetalk\/\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\/","og_site_name":"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","article_published_time":"2025-06-05T02:24:31+00:00","article_modified_time":"2025-06-05T03:05:14+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_title":"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","twitter_description":"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e21\u0e32 \u201c\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u201d \u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 \u201c\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32 \u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u201d","twitter_image":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp","twitter_misc":{"Written by":"admin","Est. reading time":"4 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#article","isPartOf":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/"},"author":{"name":"admin","@id":"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/00e11c9a5b4eeb918aad42ec1d6adfc7"},"headline":"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07","datePublished":"2025-06-05T02:24:31+00:00","dateModified":"2025-06-05T03:05:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/"},"wordCount":25,"publisher":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/#organization"},"image":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp","articleSection":["All Around"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/","url":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/","name":"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","isPartOf":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#primaryimage"},"image":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp","datePublished":"2025-06-05T02:24:31+00:00","dateModified":"2025-06-05T03:05:14+00:00","description":"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e21\u0e32 \u201c\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u201d \u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48 \u201c\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32 \u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u201d","breadcrumb":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#primaryimage","url":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp","contentUrl":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp","width":1920,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmc.co.th\/wetalk\/%e0%b9%84%e0%b8%82%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cmc.co.th\/wetalk\/"},{"@type":"ListItem","position":2,"name":"\u0e44\u0e02\u0e23\u0e2b\u0e31\u0e2a\u0e25\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 : \u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e07"}]},{"@type":"WebSite","@id":"https:\/\/www.cmc.co.th\/wetalk\/#website","url":"https:\/\/www.cmc.co.th\/wetalk\/","name":"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","description":"CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","publisher":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmc.co.th\/wetalk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.cmc.co.th\/wetalk\/#organization","name":"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","url":"https:\/\/www.cmc.co.th\/wetalk\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/logo\/image\/","url":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2021\/01\/cropped-t.jpg","contentUrl":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2021\/01\/cropped-t.jpg","width":150,"height":150,"caption":"CMC WE TALK |  CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14"},"image":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/00e11c9a5b4eeb918aad42ec1d6adfc7","name":"admin","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2b95b7349d23f2efc89b243b406187035f772e87867edf3bb4398abc87dcc097?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b95b7349d23f2efc89b243b406187035f772e87867edf3bb4398abc87dcc097?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cmc.co.th\/wetalk"],"url":"https:\/\/www.cmc.co.th\/wetalk\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/allaround-\u0e17\u0e33\u0e44\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e38\u0e48\u0e075.webp","_links":{"self":[{"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/posts\/8192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/comments?post=8192"}],"version-history":[{"count":50,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/posts\/8192\/revisions"}],"predecessor-version":[{"id":8244,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/posts\/8192\/revisions\/8244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/media\/8160"}],"wp:attachment":[{"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/media?parent=8192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/categories?post=8192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/tags?post=8192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}