{"id":8380,"date":"2025-06-23T16:42:08","date_gmt":"2025-06-23T09:42:08","guid":{"rendered":"https:\/\/www.cmc.co.th\/wetalk\/?p=8380"},"modified":"2025-06-24T11:06:13","modified_gmt":"2025-06-24T04:06:13","slug":"15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94","status":"publish","type":"post","link":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/","title":{"rendered":"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 &#8211; \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8380\" class=\"elementor elementor-8380\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ab542c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ab542c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e791b24\" data-id=\"e791b24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7501861 elementor-widget elementor-widget-heading\" data-id=\"7501861\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 - \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f71bb8 elementor-widget elementor-widget-image\" data-id=\"2f71bb8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-19-scaled.webp\" class=\"attachment-full size-full wp-image-8376\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-19-scaled.webp 2560w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-19-300x169.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-19-1024x576.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-19-768x432.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-19-1536x864.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-19-2048x1152.webp 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6b0a98 elementor-widget elementor-widget-text-editor\" data-id=\"d6b0a98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e40\u0e27\u0e25\u0e32\u0e01\u0e47\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e21\u0e35 \u0e08\u0e30\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a\u0e01\u0e47\u0e22\u0e38\u0e48\u0e07\u0e22\u0e32\u0e01 \u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e39\u0e41\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e14\u0e39\u0e44\u0e01\u0e25\u0e40\u0e01\u0e34\u0e19\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e21 ?\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-055f277 elementor-widget elementor-widget-text-editor\" data-id=\"055f277\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e42\u0e22\u0e04\u0e30\u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e40\u0e01\u0e34\u0e19\u0e04\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49 \u0e0a\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e15\u0e34\u0e14\u0e43\u0e08 ! \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c680a25 elementor-widget elementor-widget-text-editor\" data-id=\"c680a25\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong><em>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e49\u0e27\u2026 \u0e44\u0e1b\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e15\u0e35\u0e49\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e40\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22 !<\/em><\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-166b910 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"166b910\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4ba66fa\" data-id=\"4ba66fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5574fd elementor-widget elementor-widget-image\" data-id=\"d5574fd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-01-1024x1024.webp\" class=\"attachment-large size-large wp-image-8377\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-01-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-01-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-01-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-01-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-01-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-01-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-988dee7\" data-id=\"988dee7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e10c5d elementor-widget elementor-widget-image\" data-id=\"1e10c5d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-02-1024x1024.webp\" class=\"attachment-large size-large wp-image-8378\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-02-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-02-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-02-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-02-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-02-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-02-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4d1a20f\" data-id=\"4d1a20f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61af812 elementor-widget elementor-widget-image\" data-id=\"61af812\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-03-1024x1024.webp\" class=\"attachment-large size-large wp-image-8379\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-03-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-03-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-03-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-03-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-03-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-03-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-54eee73 elementor-widget elementor-widget-text-editor\" data-id=\"54eee73\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>1. \u0e17\u0e48\u0e32\u0e19\u0e31\u0e48\u0e07\u0e40\u0e1e\u0e0a\u0e23 (Diamond Pose) <\/strong>&#8211; \u0e2a\u0e27\u0e22\u0e08\u0e32\u0e01\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e22\u0e48\u0e2d\u0e22 \u0e1e\u0e32\u0e43\u0e08\u0e2a\u0e07\u0e1a\n\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e22\u0e48\u0e2d\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e21\u0e32\u0e18\u0e34 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e14\u0e38\u0e25\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e43\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e33\u0e07\u0e48\u0e32\u0e22\u0e21\u0e32\u0e01\u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e36\u0e01 \n\n<br>\n<strong style=\"padding-top: 20px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e19\u0e31\u0e48\u0e07\u0e17\u0e31\u0e1a\u0e2a\u0e49\u0e19\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e25\u0e31\u0e07\u0e15\u0e23\u0e07<\/li>\n \t<li>\u0e27\u0e32\u0e07\u0e21\u0e37\u0e2d\u0e1a\u0e19\u0e15\u0e31\u0e01 \u0e2b\u0e32\u0e22\u0e43\u0e08\u0e25\u0e36\u0e01 \u0e46<\/li>\n \t<li>\u0e17\u0e33\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 5-10 \u0e19\u0e32\u0e17\u0e35<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b02a9f elementor-widget elementor-widget-text-editor\" data-id=\"7b02a9f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>2. \u0e17\u0e48\u0e32\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 (Tree Pose) <\/strong>&#8211; \u0e1d\u0e36\u0e01\u0e2a\u0e21\u0e32\u0e18\u0e34 \u0e22\u0e37\u0e14\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e17\u0e31\u0e49\u0e07\u0e15\u0e31\u0e27\n\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e43\u0e2b\u0e49\u0e02\u0e32 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e2a\u0e21\u0e32\u0e18\u0e34\u0e44\u0e1b\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e1d\u0e36\u0e01\u0e2a\u0e21\u0e14\u0e38\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e15\u0e34\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e27\u0e31\u0e19\u0e43\u0e2b\u0e21\u0e48\n\n<strong style=\"padding-top: 20px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e22\u0e37\u0e19\u0e15\u0e23\u0e07 \u0e02\u0e32\u0e0a\u0e34\u0e14\u0e01\u0e31\u0e19<\/li>\n \t<li>\u0e22\u0e01\u0e40\u0e17\u0e49\u0e32\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e27\u0e32\u0e07\u0e1a\u0e19\u0e15\u0e49\u0e19\u0e02\u0e32\u0e2d\u0e35\u0e01\u0e02\u0e49\u0e32\u0e07<\/li>\n \t<li>\u0e1e\u0e19\u0e21\u0e21\u0e37\u0e2d\u0e44\u0e27\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e39\u0e21\u0e37\u0e2d\u0e02\u0e36\u0e49\u0e19\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e28\u0e35\u0e23\u0e29\u0e30<\/li>\n \t<li>\u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e41\u0e25\u0e49\u0e27\u0e2a\u0e25\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e07<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc02447 elementor-widget elementor-widget-text-editor\" data-id=\"cc02447\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>3. \u0e17\u0e48\u0e32\u0e1e\u0e23\u0e30\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e04\u0e23\u0e36\u0e48\u0e07\u0e40\u0e2a\u0e35\u0e49\u0e22\u0e27 (Half Moon Pose)<\/strong> &#8211; \u0e1a\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e2a\u0e38\u0e14 \u0e22\u0e37\u0e14\u0e43\u0e2b\u0e49\u0e22\u0e32\u0e27 \u0e25\u0e14\u0e23\u0e2d\u0e1a\u0e40\u0e2d\u0e27\n\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e1c\u0e48\u0e19\u0e2b\u0e25\u0e31\u0e07 \u0e2a\u0e30\u0e42\u0e1e\u0e01 \u0e15\u0e49\u0e19\u0e02\u0e32 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e08\u0e31\u0e14\u0e17\u0e48\u0e27\u0e07\u0e17\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e14\u0e38\u0e25\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e42\u0e25\u0e48\u0e07\u0e2a\u0e1a\u0e32\u0e22\u0e15\u0e31\u0e27\n<br>\n<strong style=\"padding-top: 10px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e22\u0e37\u0e19\u0e15\u0e23\u0e07 \u0e40\u0e2b\u0e22\u0e35\u0e22\u0e14\u0e41\u0e02\u0e19\u0e02\u0e36\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e1a\u0e01\u0e31\u0e19<\/li>\n \t<li>\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e25\u0e33\u0e15\u0e31\u0e27\u0e44\u0e1b\u0e14\u0e49\u0e32\u0e19\u0e02\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e49\u0e32 \u0e46<\/li>\n \t<li>\u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e41\u0e25\u0e49\u0e27\u0e2a\u0e25\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e07<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8abae2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8abae2d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-68b55e0\" data-id=\"68b55e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d44c826 elementor-widget elementor-widget-image\" data-id=\"d44c826\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-04-1024x1024.webp\" class=\"attachment-large size-large wp-image-8381\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-04-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-04-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-04-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-04-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-04-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-04-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ca7116e\" data-id=\"ca7116e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abc1896 elementor-widget elementor-widget-image\" data-id=\"abc1896\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-05-1024x1024.webp\" class=\"attachment-large size-large wp-image-8382\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-05-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-05-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-05-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-05-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-05-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-05-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c441054\" data-id=\"c441054\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-858717d elementor-widget elementor-widget-image\" data-id=\"858717d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-06-1024x1024.webp\" class=\"attachment-large size-large wp-image-8383\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-06-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-06-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-06-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-06-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-06-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-06-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4b7b1e elementor-widget elementor-widget-text-editor\" data-id=\"b4b7b1e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>4. \u0e17\u0e48\u0e32\u0e2a\u0e38\u0e19\u0e31\u0e02\u0e01\u0e49\u0e21\u0e2b\u0e19\u0e49\u0e32 (Downward Dog)<\/strong>&#8211; \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e17\u0e31\u0e49\u0e07\u0e15\u0e31\u0e27 \u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a\u0e41\u0e02\u0e19-\u0e02\u0e32 \u0e22\u0e37\u0e14\u0e2b\u0e25\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e19\n\u0e2a\u0e32\u0e22\u0e22\u0e37\u0e14\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e48\u0e32\u0e19\u0e35\u0e49! \u0e22\u0e37\u0e14\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e2b\u0e25\u0e31\u0e07 \u0e41\u0e02\u0e19 \u0e02\u0e32 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e17\u0e31\u0e48\u0e27\u0e23\u0e48\u0e32\u0e07\u0e41\u0e1a\u0e1a\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e43\u0e04\u0e23\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e22\u0e25\u0e49\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e08\u0e30\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e1f\u0e34\u0e19\u0e2a\u0e38\u0e14 \u0e46\n<br>\n<strong style=\"padding-top: 20px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e04\u0e25\u0e32\u0e19<\/li>\n \t<li>\u0e22\u0e01\u0e2a\u0e30\u0e42\u0e1e\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e17\u0e33\u0e15\u0e31\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e15\u0e31\u0e27 V \u0e01\u0e25\u0e31\u0e1a\u0e2b\u0e31\u0e27<\/li>\n \t<li>\u0e01\u0e14\u0e2a\u0e49\u0e19\u0e40\u0e17\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1d\u0e48\u0e32\u0e21\u0e37\u0e2d\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19 \u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-750e66f elementor-widget elementor-widget-text-editor\" data-id=\"750e66f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>5. \u0e17\u0e48\u0e32\u0e19\u0e31\u0e01\u0e23\u0e1a (Warrior Pose) <\/strong>&#8211; \u0e40\u0e1c\u0e32\u0e1c\u0e25\u0e32\u0e0d \u0e2a\u0e30\u0e42\u0e1e\u0e01\u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a \u0e25\u0e14\u0e1b\u0e27\u0e14\u0e2b\u0e25\u0e31\u0e07\n\u0e02\u0e32 \u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a ! \u0e2a\u0e30\u0e42\u0e1e\u0e01 \u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 ! \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e48\u0e32\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e2e\u0e36\u0e14\u0e43\u0e19\u0e15\u0e31\u0e27\u0e04\u0e38\u0e13 \u0e25\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e27\u0e14\u0e2b\u0e25\u0e31\u0e07 \u0e19\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\n<br>\n\n<strong style=\"padding-top: 10px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e01\u0e32\u0e07\u0e02\u0e32\u0e2d\u0e2d\u0e01\u0e01\u0e27\u0e49\u0e32\u0e07<\/li>\n \t<li>\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e17\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32 90 \u0e2d\u0e07\u0e28\u0e32 \u0e07\u0e2d\u0e40\u0e02\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e19\u0e02\u0e32\u0e02\u0e19\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19<\/li>\n \t<li>\u0e01\u0e32\u0e07\u0e41\u0e02\u0e19\u0e02\u0e19\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19 \u0e21\u0e2d\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27<\/li>\n<li>\u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e41\u0e25\u0e49\u0e27\u0e2a\u0e25\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e07<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6c2e46 elementor-widget elementor-widget-text-editor\" data-id=\"e6c2e46\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>6. \u0e17\u0e48\u0e32\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 (Chair Pose) <\/strong>&#8211; \u0e15\u0e49\u0e19\u0e02\u0e32\u0e41\u0e19\u0e48\u0e19 \u0e2a\u0e30\u0e42\u0e1e\u0e01\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e2b\u0e31\u0e27\u0e43\u0e08\u0e1f\u0e34\u0e15\n\u0e1a\u0e39\u0e2a\u0e15\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e02\u0e32 \u0e41\u0e02\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e25\u0e31\u0e07\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1a\u0e34\u0e23\u0e4c\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e44\u0e2b\u0e19 \u0e22\u0e37\u0e19\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e01\u0e47\u0e1f\u0e34\u0e15\u0e44\u0e14\u0e49 !\n<br>\n<strong style=\"padding-top: 20px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e22\u0e37\u0e19\u0e40\u0e17\u0e49\u0e32\u0e0a\u0e34\u0e14 \u0e22\u0e01\u0e41\u0e02\u0e19\u0e02\u0e36\u0e49\u0e19\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e28\u0e35\u0e23\u0e29\u0e30<\/li>\n \t<li>\u0e07\u0e2d\u0e40\u0e02\u0e48\u0e32\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49<\/li>\n \t<li>\u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 30-60 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f72de36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f72de36\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-184d63a\" data-id=\"184d63a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a979bc elementor-widget elementor-widget-image\" data-id=\"0a979bc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-07-1024x1024.webp\" class=\"attachment-large size-large wp-image-8384\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-07-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-07-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-07-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-07-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-07-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-07-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-030e782\" data-id=\"030e782\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-583c04a elementor-widget elementor-widget-image\" data-id=\"583c04a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-08-1024x1024.webp\" class=\"attachment-large size-large wp-image-8385\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-08-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-08-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-08-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-08-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-08-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-08-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3e0278c\" data-id=\"3e0278c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4684544 elementor-widget elementor-widget-image\" data-id=\"4684544\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-09-1024x1024.webp\" class=\"attachment-large size-large wp-image-8386\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-09-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-09-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-09-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-09-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-09-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-09-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c13a99f elementor-widget elementor-widget-text-editor\" data-id=\"c13a99f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>7. \u0e17\u0e48\u0e32\u0e15\u0e23\u0e35\u0e42\u0e01\u0e13 (Triangle Pose)<\/strong>) &#8211; \u0e22\u0e37\u0e14\u0e2b\u0e25\u0e31\u0e07 \u0e40\u0e2d\u0e27\u0e1a\u0e32\u0e07 \u0e2a\u0e30\u0e42\u0e1e\u0e01\u0e40\u0e14\u0e49\u0e07\n\u0e1b\u0e25\u0e38\u0e01\u0e1a\u0e31\u0e49\u0e19\u0e17\u0e49\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e15\u0e37\u0e48\u0e19 ! \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e30\u0e42\u0e1e\u0e01 \u0e02\u0e32 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e01\u0e32\u0e23\u0e22\u0e37\u0e14\u0e40\u0e2b\u0e22\u0e35\u0e22\u0e14\u0e01\u0e23\u0e30\u0e14\u0e39\u0e01\u0e2a\u0e31\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e15\u0e23\u0e07\u0e2a\u0e27\u0e22\n<br>\n<strong style=\"padding-top: 20px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e22\u0e37\u0e19\u0e01\u0e32\u0e07\u0e02\u0e32\u0e01\u0e27\u0e49\u0e32\u0e07<\/li>\n \t<li>\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e15\u0e31\u0e27\u0e41\u0e15\u0e30\u0e02\u0e49\u0e2d\u0e40\u0e17\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e21\u0e37\u0e2d\u0e02\u0e49\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2d\u0e35\u0e01\u0e02\u0e49\u0e32\u0e07\u0e0a\u0e39\u0e02\u0e36\u0e49\u0e19<\/li>\n \t<li>\u0e21\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e0a\u0e39\u0e02\u0e36\u0e49\u0e19 \u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b62e5c elementor-widget elementor-widget-text-editor\" data-id=\"5b62e5c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>8. \u0e17\u0e48\u0e32\u0e2d\u0e39\u0e10 (Camel Pose) <\/strong>\u2013 \u0e41\u0e2d\u0e48\u0e19\u0e2d\u0e01 \u0e40\u0e1b\u0e34\u0e14\u0e43\u0e08 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e25\u0e31\u0e07\n\u0e40\u0e1b\u0e34\u0e14\u0e2d\u0e01 \u0e40\u0e1b\u0e34\u0e14\u0e43\u0e08 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e22\u0e37\u0e14\u0e0a\u0e48\u0e27\u0e07\u0e25\u0e33\u0e15\u0e31\u0e27 \u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e01 \u0e15\u0e49\u0e19\u0e02\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e49\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e15\u0e37\u0e48\u0e19\u0e40\u0e15\u0e47\u0e21\u0e15\u0e32\u0e41\u0e1a\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\n\n<strong style=\"padding-top: 10px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e04\u0e38\u0e01\u0e40\u0e02\u0e48\u0e32 \u0e27\u0e32\u0e07\u0e21\u0e37\u0e2d\u0e1a\u0e19\u0e2a\u0e49\u0e19\u0e40\u0e17\u0e49\u0e32<\/li>\n \t<li>\u0e41\u0e2d\u0e48\u0e19\u0e2b\u0e25\u0e31\u0e07 \u0e40\u0e07\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e36\u0e49\u0e19<\/li>\n \t<li>\u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 20-30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e25\u0e31\u0e1a\u0e2a\u0e39\u0e48\u0e17\u0e48\u0e32\u0e1b\u0e01\u0e15\u0e34<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6ae12b elementor-widget elementor-widget-text-editor\" data-id=\"d6ae12b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>9. \u0e17\u0e48\u0e32\u0e1a\u0e34\u0e14\u0e15\u0e31\u0e27 (Twist Pose) <\/strong>&#8211; \u0e22\u0e37\u0e14\u0e40\u0e2d\u0e27 \u0e04\u0e25\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07 \u0e1b\u0e25\u0e14\u0e25\u0e47\u0e2d\u0e01\u0e04\u0e27\u0e32\u0e21\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e22\n\u0e25\u0e14\u0e1b\u0e27\u0e14\u0e2b\u0e25\u0e31\u0e07 \u0e22\u0e37\u0e14\u0e2b\u0e25\u0e31\u0e07 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e1a\u0e34\u0e14\u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2a\u0e21\u0e14\u0e38\u0e25 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e22\u0e47\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\n<br>\n\n<strong style=\"padding-top: 20px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e19\u0e2d\u0e19\u0e2b\u0e07\u0e32\u0e22 \u0e07\u0e2d\u0e40\u0e02\u0e48\u0e32\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1e\u0e32\u0e14\u0e02\u0e49\u0e32\u0e21\u0e25\u0e33\u0e15\u0e31\u0e27<\/li>\n \t<li>\u0e21\u0e37\u0e2d\u0e02\u0e49\u0e32\u0e07\u0e15\u0e23\u0e07\u0e02\u0e49\u0e32\u0e21\u0e14\u0e31\u0e19\u0e40\u0e02\u0e48\u0e32\u0e44\u0e27\u0e49\u0e40\u0e1a\u0e32 \u0e46<\/li>\n \t<li>\u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e41\u0e25\u0e49\u0e27\u0e2a\u0e25\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e07<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-deb0cc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"deb0cc0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-20011ce\" data-id=\"20011ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dec3884 elementor-widget elementor-widget-image\" data-id=\"dec3884\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-10-1024x1024.webp\" class=\"attachment-large size-large wp-image-8388\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-10-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-10-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-10-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-10-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-10-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-10-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ca41066\" data-id=\"ca41066\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d66b87 elementor-widget elementor-widget-image\" data-id=\"2d66b87\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-11-1024x1024.webp\" class=\"attachment-large size-large wp-image-8389\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-11-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-11-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-11-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-11-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-11-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-11-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-374daba\" data-id=\"374daba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a83f836 elementor-widget elementor-widget-image\" data-id=\"a83f836\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-12-1024x1024.webp\" class=\"attachment-large size-large wp-image-8390\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-12-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-12-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-12-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-12-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-12-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-12-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-94d4500 elementor-widget elementor-widget-text-editor\" data-id=\"94d4500\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>10. \u0e17\u0e48\u0e32\u0e07\u0e39 (Cobra Pose) <\/strong> \u2013 \u0e1b\u0e25\u0e38\u0e01\u0e01\u0e23\u0e30\u0e14\u0e39\u0e01\u0e2a\u0e31\u0e19\u0e2b\u0e25\u0e31\u0e07 \u0e41\u0e01\u0e49\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e48\u0e2d\u0e21 \u0e22\u0e37\u0e14\u0e2a\u0e30\u0e42\u0e1e\u0e01\u0e2a\u0e38\u0e14\u0e1f\u0e34\u0e19\n\u0e1b\u0e25\u0e38\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e25\u0e33\u0e15\u0e31\u0e27 ! \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e01 \u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e21\u0e19\u0e32\u0e19 \u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e44\u0e2b\u0e25\u0e48\u0e2b\u0e48\u0e2d\n<br>\n\n<strong style=\"padding-top: 20px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e19\u0e2d\u0e19\u0e04\u0e27\u0e48\u0e33 \u0e27\u0e32\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e15\u0e49\u0e2b\u0e31\u0e27\u0e44\u0e2b\u0e25\u0e48<\/li>\n \t<li>\u0e14\u0e31\u0e19\u0e15\u0e31\u0e27\u0e02\u0e36\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e01\u0e40\u0e1b\u0e34\u0e14 \u0e2a\u0e30\u0e42\u0e1e\u0e01\u0e22\u0e31\u0e07\u0e41\u0e19\u0e1a\u0e1e\u0e37\u0e49\u0e19<\/li>\n \t<li>\u0e40\u0e07\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 15-30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-098dff6 elementor-widget elementor-widget-text-editor\" data-id=\"098dff6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>11. \u0e17\u0e48\u0e32\u0e28\u0e1e (Corpse Pose) <\/strong>&#8211; \u0e1e\u0e31\u0e01\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e27\u0e32\u0e07\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e42\u0e25\u0e48\u0e07 \u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2b\u0e32\u0e22\u0e43\u0e08\n\u0e2d\u0e22\u0e48\u0e32\u0e14\u0e39\u0e16\u0e39\u0e01\u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e22\u0e1a\u0e04\u0e37\u0e2d\u0e1e\u0e25\u0e31\u0e07 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e36\u0e01\u0e0b\u0e36\u0e49\u0e07 \u0e08\u0e34\u0e15\u0e43\u0e08\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2b\u0e25\u0e31\u0e1a\u0e2a\u0e19\u0e34\u0e17\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e36\u0e48\u0e07\u0e41\u0e2d\u0e1b\n<br>\n\n<strong style=\"padding-top: 10px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e19\u0e2d\u0e19\u0e2b\u0e07\u0e32\u0e22 \u0e41\u0e02\u0e19\u0e02\u0e32\u0e27\u0e32\u0e07\u0e2a\u0e1a\u0e32\u0e22<\/li>\n \t<li>\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22<\/li>\n \t<li>\u0e2b\u0e32\u0e22\u0e43\u0e08\u0e25\u0e36\u0e01 \u0e46 \u0e19\u0e34\u0e48\u0e07 \u0e46 \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 5-10 \u0e19\u0e32\u0e17\u0e35<\/li>\n \t\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd4b642 elementor-widget elementor-widget-text-editor\" data-id=\"dd4b642\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>12. \u0e17\u0e48\u0e32\u0e19\u0e31\u0e48\u0e07\u0e1a\u0e34\u0e14\u0e15\u0e31\u0e27 (Seated Twist)<\/strong>&#8211; \u0e14\u0e35\u0e17\u0e47\u0e2d\u0e01\u0e0b\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e22\u0e48\u0e2d\u0e22 \u0e1c\u0e2d\u0e21\u0e08\u0e32\u0e01\u0e20\u0e32\u0e22\u0e43\u0e19\n\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e25\u0e31\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e22\u0e48\u0e2d\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e14\u0e38\u0e25\u0e01\u0e23\u0e30\u0e14\u0e39\u0e01\u0e2a\u0e31\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e15\u0e23\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\n<br>\n<strong style=\"padding-top: 20px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e2b\u0e25\u0e31\u0e07\u0e15\u0e23\u0e07 \u0e02\u0e32\u0e0a\u0e34\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e31\u0e14\u0e2a\u0e21\u0e32\u0e18\u0e34<\/li>\n \t<li>\u0e1a\u0e34\u0e14\u0e25\u0e33\u0e15\u0e31\u0e27\u0e44\u0e1b\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e21\u0e37\u0e2d\u0e41\u0e15\u0e30\u0e40\u0e02\u0e48\u0e32\u0e2d\u0e35\u0e01\u0e02\u0e49\u0e32\u0e07<\/li>\n \t<li>\u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e41\u0e25\u0e49\u0e27\u0e2a\u0e25\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e07<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d3d2871 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3d2871\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d5c10f5\" data-id=\"d5c10f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0f2376 elementor-widget elementor-widget-image\" data-id=\"b0f2376\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-13-1024x1024.webp\" class=\"attachment-large size-large wp-image-8391\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-13-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-13-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-13-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-13-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-13-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-13-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4ca5aa5\" data-id=\"4ca5aa5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ed5cb0 elementor-widget elementor-widget-image\" data-id=\"7ed5cb0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-14-1024x1024.webp\" class=\"attachment-large size-large wp-image-8392\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-14-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-14-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-14-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-14-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-14-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-14-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e4c4d5a\" data-id=\"e4c4d5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd7eaa8 elementor-widget elementor-widget-image\" data-id=\"dd7eaa8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-15-1024x1024.webp\" class=\"attachment-large size-large wp-image-8393\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-15-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-15-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-15-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-15-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-15-1536x1536.webp 1536w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/\u0e17\u0e48\u0e32-15-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2d8748 elementor-widget elementor-widget-text-editor\" data-id=\"a2d8748\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>13. \u0e17\u0e48\u0e32\u0e2a\u0e30\u0e1e\u0e32\u0e19 (Bridge Pose)<\/strong> &#8211; \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21\u0e23\u0e2d\u0e1a\u0e15\u0e31\u0e27 \u0e25\u0e14\u0e44\u0e02\u0e21\u0e31\u0e19\u0e40\u0e2d\u0e27 \u0e2b\u0e25\u0e31\u0e07 \u0e2a\u0e30\u0e42\u0e1e\u0e01\n\u0e1f\u0e34\u0e15\u0e2b\u0e25\u0e31\u0e07 \u0e41\u0e02\u0e19 \u0e2a\u0e30\u0e42\u0e1e\u0e01 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e41\u0e25\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e32\u0e22\u0e43\u0e08\u0e44\u0e14\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e21\u0e32\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1d\u0e36\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e34\u0e01\u0e07\u0e32\u0e19\n<br>\n<strong style=\"padding-top: 20px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e19\u0e2d\u0e19\u0e2b\u0e07\u0e32\u0e22 \u0e0a\u0e31\u0e19\u0e40\u0e02\u0e48\u0e32 \u0e40\u0e17\u0e49\u0e32\u0e27\u0e32\u0e07\u0e41\u0e19\u0e1a\u0e1e\u0e37\u0e49\u0e19<\/li>\n \t<li>\u0e22\u0e01\u0e2a\u0e30\u0e42\u0e1e\u0e01\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e39\u0e07<\/li>\n \t<li>\u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 15-30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e41\u0e25\u0e49\u0e27\u0e27\u0e32\u0e07\u0e25\u0e07<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c4ef2d elementor-widget elementor-widget-text-editor\" data-id=\"3c4ef2d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>14. \u0e17\u0e48\u0e32\u0e27\u0e32\u0e07\u0e02\u0e32\u0e1a\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07 (Legs Up The Wall Pose) (Corpse Pose) <\/strong>&#8211; \u0e40\u0e17\u0e49\u0e32\u0e1e\u0e31\u0e01 \u0e2a\u0e21\u0e2d\u0e07\u0e40\u0e1a\u0e32 \u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e41\u0e1a\u0e1a\u0e40\u0e15\u0e47\u0e21\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c\n\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e40\u0e17\u0e49\u0e32\u0e1a\u0e27\u0e21 ! \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e44\u0e2b\u0e25\u0e40\u0e27\u0e35\u0e22\u0e19\u0e14\u0e35 \u0e19\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e19\u0e2b\u0e19\u0e31\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e07\u0e21\u0e32\u0e44\u0e14\u0e49\u0e14\u0e35\u0e2a\u0e38\u0e14 \u0e46\n<br>\n<strong style=\"padding-top: 10px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e19\u0e2d\u0e19\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19 \u0e1e\u0e32\u0e14\u0e02\u0e32\u0e02\u0e36\u0e49\u0e19\u0e1a\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07<\/li>\n \t<li>\u0e43\u0e2b\u0e49\u0e01\u0e49\u0e19\u0e0a\u0e34\u0e14\u0e1c\u0e19\u0e31\u0e07\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/li>\n \t<li>\u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 5-15 \u0e19\u0e32\u0e17\u0e35 \u0e2b\u0e32\u0e22\u0e43\u0e08\u0e25\u0e36\u0e01 \u0e46<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7d8ae6 elementor-widget elementor-widget-text-editor\" data-id=\"b7d8ae6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>15. \u0e17\u0e48\u0e32\u0e40\u0e14\u0e47\u0e01 (Child\u2019s Pose) <\/strong>\u2013 \u0e1f\u0e35\u0e25\u0e01\u0e39\u0e49\u0e14 \u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07 \u0e25\u0e14\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e17\u0e31\u0e19\u0e15\u0e32\n\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e48\u0e2d\u0e22\u0e25\u0e49\u0e32 \u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e25\u0e48\u0e32\u0e07 \u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e27\u0e14\u0e2b\u0e25\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e22\u0e48\u0e2d\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\n<br><strong style=\"padding-top: 20px;\">\u0e27\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01:<\/strong>\n<ol style=\"padding-left: 10px;\">\n \t<li>\u0e04\u0e38\u0e01\u0e40\u0e02\u0e48\u0e32 \u0e01\u0e49\u0e21\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e2b\u0e19\u0e49\u0e32\u0e1c\u0e32\u0e01\u0e41\u0e19\u0e1a\u0e1e\u0e37\u0e49\u0e19<\/li>\n \t<li>\u0e40\u0e2b\u0e22\u0e35\u0e22\u0e14\u0e41\u0e02\u0e19\u0e44\u0e1b\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32<\/li>\n \t<li>\u0e04\u0e49\u0e32\u0e07\u0e44\u0e27\u0e49 1-3 \u0e19\u0e32\u0e17\u0e35<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12b4a50 elementor-widget elementor-widget-text-editor\" data-id=\"12b4a50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e42\u0e22\u0e04\u0e30\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e04\u0e34\u0e14 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1f\u0e37\u0e49\u0e19\u0e04\u0e37\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49  \u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e40\u0e23\u0e32\u0e04\u0e31\u0e14\u0e21\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e42\u0e14\u0e22\u0e40\u0e23\u0e35\u0e22\u0e07\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e17\u0e48\u0e32\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1d\u0e36\u0e01\u0e27\u0e31\u0e19\u0e25\u0e30 2-3 \u0e17\u0e48\u0e32\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e40\u0e0b\u0e15 15-20 \u0e19\u0e32\u0e17\u0e35\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e0a\u0e49\u0e32\/\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e41\u0e04\u0e48\u0e21\u0e35\u0e1e\u0e23\u0e21\u0e42\u0e22\u0e04\u0e30\u0e41\u0e1c\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e01\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e49\u0e32\u0e07\u0e40\u0e15\u0e35\u0e22\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e25\u0e32\u0e22\u0e42\u0e0b\u0e1f\u0e32 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e1b\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e07\u0e49\u0e2d\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3afe33 elementor-widget elementor-widget-text-editor\" data-id=\"c3afe33\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 www.cmc.co.th <\/strong><strong>\u0e2b\u0e23\u0e37\u0e2d Call center 1172 <\/strong><strong>\u0e41\u0e25\u0e30 Facebook Fanpage : CMC Group (*<\/strong><strong>\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f\u0e01\u0e33\u0e2b\u0e19\u0e14)<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-75d62e0\" data-id=\"75d62e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a6f47b elementor-widget elementor-widget-text-editor\" data-id=\"4a6f47b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4397\" class=\"elementor elementor-4397\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e561d41 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e561d41\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e730739\" data-id=\"e730739\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efe2678 elementor-widget elementor-widget-heading\" data-id=\"efe2678\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CMC We Talk<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4f5593 elementor-widget elementor-widget-text-editor\" data-id=\"d4f5593\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d94be4f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d94be4f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b246e2 elementor-widget elementor-widget-text-editor\" data-id=\"7b246e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLatest Content \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0068340 elementor-grid-eael-col-1 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"0068340\" data-element_type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-1&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"eael-post-grid-0068340\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-0068340 eael-post-grid-style-two\" data-layout-mode=\"grid\"><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"8647\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/www.cmc.co.th\/wetalk\/cmc-%e0%b8%88%e0%b8%b1%e0%b8%9a%e0%b8%a1%e0%b8%b7%e0%b8%ad-%e0%b8%a1-%e0%b8%a8%e0%b8%a3%e0%b8%b5%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1-%e0%b8%94%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a1%e0%b9%80%e0%b8%94\/\"><\/a><\/div><div class=\"eael-entry-thumbnail \">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d-1024x1024.webp\" class=\"attachment-large size-large wp-image-8653\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d-1024x1024.webp 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d-300x300.webp 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d-150x150.webp 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d-768x768.webp 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2026\/02\/\u0e23\u0e39\u0e1b\u0e1b\u0e01d.webp 1244w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n                              <\/div>\n                      <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/www.cmc.co.th\/wetalk\/cmc-%e0%b8%88%e0%b8%b1%e0%b8%9a%e0%b8%a1%e0%b8%b7%e0%b8%ad-%e0%b8%a1-%e0%b8%a8%e0%b8%a3%e0%b8%b5%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1-%e0%b8%94%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a1%e0%b9%80%e0%b8%94\/\" title=\"CMC \u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e21.\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e14\u0e31\u0e19\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e2f\u200b \u200b\u200b\u0e40\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e32\u0e21\u0e08\u0e23\u0e34\u0e07 \u201cCMC Student Affiliate\u201d \u0e1b\u0e31\u0e49\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u200b\">CMC \u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e21.\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e14\u0e31\u0e19\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e2f\u200b \u200b\u200b\u0e40\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e32\u0e21\u0e08\u0e23\u0e34\u0e07 \u201cCMC Student Affiliate\u201d \u0e1b\u0e31\u0e49\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u200b<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                    <div class=\"eael-grid-post-excerpt\"><a\n                                        href=\"https:\/\/www.cmc.co.th\/wetalk\/cmc-%e0%b8%88%e0%b8%b1%e0%b8%9a%e0%b8%a1%e0%b8%b7%e0%b8%ad-%e0%b8%a1-%e0%b8%a8%e0%b8%a3%e0%b8%b5%e0%b8%9b%e0%b8%97%e0%b8%b8%e0%b8%a1-%e0%b8%94%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a1%e0%b9%80%e0%b8%94\/\"\n                                        class=\"eael-post-elements-readmore-btn\">Read More<\/a><\/div>\n                                <\/div><div class=\"eael-entry-header-after style-two\"><div class=\"eael-entry-meta\"><span class=\"eael-meta-posted-on\"><i class=\"far fa-clock\"><\/i><time datetime=\"12 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2026\">12 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"8601\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/www.cmc.co.th\/wetalk\/10-%e0%b8%ad%e0%b8%b1%e0%b8%99%e0%b8%94%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%b1%e0%b8%95%e0%b8%a7%e0%b9%8c%e0%b9%80%e0%b8%a5%e0%b8%b5%e0%b9%89%e0%b8%a2%e0%b8%87%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%99\/\"><\/a><\/div><div class=\"eael-entry-thumbnail \">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012-1024x1024.jpg\" class=\"attachment-large size-large wp-image-8598\" alt=\"\" srcset=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012-1024x1024.jpg 1024w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012-300x300.jpg 300w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012-150x150.jpg 150w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012-768x768.jpg 768w, https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/11\/IMC-\u0e2a\u0e34\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07-012.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n                              <\/div>\n                      <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/www.cmc.co.th\/wetalk\/10-%e0%b8%ad%e0%b8%b1%e0%b8%99%e0%b8%94%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%b1%e0%b8%95%e0%b8%a7%e0%b9%8c%e0%b9%80%e0%b8%a5%e0%b8%b5%e0%b9%89%e0%b8%a2%e0%b8%87%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%99\/\" title=\"10 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e22\u0e2d\u0e14\u0e19\u0e34\u0e22\u0e21\u0e43\u0e19\u0e44\u0e17\u0e22 \u0e1b\u0e35 2025 \u2013 \u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e04\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e39\u0e49!\">10 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e22\u0e2d\u0e14\u0e19\u0e34\u0e22\u0e21\u0e43\u0e19\u0e44\u0e17\u0e22 \u0e1b\u0e35 2025 \u2013 \u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e04\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e39\u0e49!<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                    <div class=\"eael-grid-post-excerpt\"><a\n                                        href=\"https:\/\/www.cmc.co.th\/wetalk\/10-%e0%b8%ad%e0%b8%b1%e0%b8%99%e0%b8%94%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%b1%e0%b8%95%e0%b8%a7%e0%b9%8c%e0%b9%80%e0%b8%a5%e0%b8%b5%e0%b9%89%e0%b8%a2%e0%b8%87%e0%b8%a2%e0%b8%ad%e0%b8%94%e0%b8%99\/\"\n                                        class=\"eael-post-elements-readmore-btn\">Read More<\/a><\/div>\n                                <\/div><div class=\"eael-entry-header-after style-two\"><div class=\"eael-entry-meta\"><span class=\"eael-meta-posted-on\"><i class=\"far fa-clock\"><\/i><time datetime=\"21 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2025\">21 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2025<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>            <div class=\"eael-load-more-button-wrap\">\n                <button class=\"eael-load-more-button\" id=\"eael-load-more-btn-0068340\" data-widget-id=\"0068340\" data-widget=\"0068340\" data-page-id=\"4397\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;default.php&quot;,&quot;name&quot;:&quot;Post-Grid&quot;}\" data-class=\"Essential_Addons_Elementor\\Elements\\Post_Grid\" data-layout=\"grid\" data-page=\"1\" data-args=\"orderby=date&amp;order=desc&amp;ignore_sticky_posts=1&amp;post_status=publish&amp;posts_per_page=2&amp;offset=0&amp;post_type=post&amp;tax_query%5B0%5D%5Btaxonomy%5D=category&amp;tax_query%5B0%5D%5Bfield%5D=term_id&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=21&amp;tax_query%5B0%5D%5Bterms%5D%5B1%5D=25&amp;tax_query%5Brelation%5D=AND\" data-max-page=\"164\">\n                    <span class=\"eael-btn-loader button__loader\"><\/span>\n                    <span class=\"eael_load_more_text\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\n                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e42\u0e22\u0e04\u0e30\u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e40\u0e01\u0e34\u0e19\u0e04\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49 \u0e0a\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e15\u0e34\u0e14\u0e43\u0e08 !<\/p>\n","protected":false},"author":1,"featured_media":8375,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_canvas","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-8380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-around","odd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 - \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14<\/title>\n<meta name=\"description\" content=\"\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e42\u0e22\u0e04\u0e30\u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e40\u0e01\u0e34\u0e19\u0e04\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49 \u0e0a\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e15\u0e34\u0e14\u0e43\u0e08 !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmc.co.th\/wetalk\/15\u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 - \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\" \/>\n<meta property=\"og:description\" content=\"\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e42\u0e22\u0e04\u0e30\u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e40\u0e01\u0e34\u0e19\u0e04\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49 \u0e0a\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e15\u0e34\u0e14\u0e43\u0e08 !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmc.co.th\/wetalk\/15\u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14\/\" \/>\n<meta property=\"og:site_name\" content=\"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-23T09:42:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-24T04:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 - \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\" \/>\n<meta name=\"twitter:description\" content=\"\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e42\u0e22\u0e04\u0e30\u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e40\u0e01\u0e34\u0e19\u0e04\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49 \u0e0a\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e15\u0e34\u0e14\u0e43\u0e08 !\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/00e11c9a5b4eeb918aad42ec1d6adfc7\"},\"headline\":\"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 &#8211; \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\",\"datePublished\":\"2025-06-23T09:42:08+00:00\",\"dateModified\":\"2025-06-24T04:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/\"},\"wordCount\":78,\"publisher\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp\",\"articleSection\":[\"All Around\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/\",\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/\",\"name\":\"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 - \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\",\"isPartOf\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp\",\"datePublished\":\"2025-06-23T09:42:08+00:00\",\"dateModified\":\"2025-06-24T04:06:13+00:00\",\"description\":\"\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e42\u0e22\u0e04\u0e30\u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e40\u0e01\u0e34\u0e19\u0e04\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49 \u0e0a\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e15\u0e34\u0e14\u0e43\u0e08 !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#primaryimage\",\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp\",\"contentUrl\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cmc.co.th\/wetalk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 &#8211; \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#website\",\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/\",\"name\":\"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\",\"description\":\"CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\",\"publisher\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cmc.co.th\/wetalk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#organization\",\"name\":\"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\",\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2021\/01\/cropped-t.jpg\",\"contentUrl\":\"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2021\/01\/cropped-t.jpg\",\"width\":150,\"height\":150,\"caption\":\"CMC WE TALK |  CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\"},\"image\":{\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/00e11c9a5b4eeb918aad42ec1d6adfc7\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b95b7349d23f2efc89b243b406187035f772e87867edf3bb4398abc87dcc097?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b95b7349d23f2efc89b243b406187035f772e87867edf3bb4398abc87dcc097?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/www.cmc.co.th\/wetalk\"],\"url\":\"https:\/\/www.cmc.co.th\/wetalk\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 - \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","description":"\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e42\u0e22\u0e04\u0e30\u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e40\u0e01\u0e34\u0e19\u0e04\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49 \u0e0a\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e15\u0e34\u0e14\u0e43\u0e08 !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmc.co.th\/wetalk\/15\u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14\/","og_locale":"th_TH","og_type":"article","og_title":"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 - \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","og_description":"\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e42\u0e22\u0e04\u0e30\u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e40\u0e01\u0e34\u0e19\u0e04\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49 \u0e0a\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e15\u0e34\u0e14\u0e43\u0e08 !","og_url":"https:\/\/www.cmc.co.th\/wetalk\/15\u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14\/","og_site_name":"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","article_published_time":"2025-06-23T09:42:08+00:00","article_modified_time":"2025-06-24T04:06:13+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_title":"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 - \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","twitter_description":"\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e42\u0e22\u0e04\u0e30\u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e40\u0e01\u0e34\u0e19\u0e04\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49 \u0e0a\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e15\u0e34\u0e14\u0e43\u0e08 !","twitter_image":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp","twitter_misc":{"Written by":"admin","Est. reading time":"6 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#article","isPartOf":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/"},"author":{"name":"admin","@id":"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/00e11c9a5b4eeb918aad42ec1d6adfc7"},"headline":"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 &#8211; \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14","datePublished":"2025-06-23T09:42:08+00:00","dateModified":"2025-06-24T04:06:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/"},"wordCount":78,"publisher":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/#organization"},"image":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp","articleSection":["All Around"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/","url":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/","name":"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 - \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 | CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","isPartOf":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#primaryimage"},"image":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp","datePublished":"2025-06-23T09:42:08+00:00","dateModified":"2025-06-24T04:06:13+00:00","description":"\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e42\u0e22\u0e04\u0e30\u0e17\u0e31\u0e49\u0e07 15 \u0e17\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e40\u0e01\u0e34\u0e19\u0e04\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49 \u0e0a\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e15\u0e34\u0e14\u0e43\u0e08 !","breadcrumb":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#primaryimage","url":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp","contentUrl":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmc.co.th\/wetalk\/15%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b9%82%e0%b8%a2%e0%b8%84%e0%b8%b0%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%8a%e0%b8%b2%e0%b8%a7%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cmc.co.th\/wetalk\/"},{"@type":"ListItem","position":2,"name":"15 \u0e17\u0e48\u0e32\u0e42\u0e22\u0e04\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e04\u0e2d\u0e19\u0e42\u0e14 &#8211; \u0e1f\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14"}]},{"@type":"WebSite","@id":"https:\/\/www.cmc.co.th\/wetalk\/#website","url":"https:\/\/www.cmc.co.th\/wetalk\/","name":"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","description":"CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","publisher":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmc.co.th\/wetalk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.cmc.co.th\/wetalk\/#organization","name":"CMC WE TALK | CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14","url":"https:\/\/www.cmc.co.th\/wetalk\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/logo\/image\/","url":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2021\/01\/cropped-t.jpg","contentUrl":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2021\/01\/cropped-t.jpg","width":150,"height":150,"caption":"CMC WE TALK |  CMC \u0e2a\u0e32\u0e23\u0e30\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14"},"image":{"@id":"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/00e11c9a5b4eeb918aad42ec1d6adfc7","name":"admin","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.cmc.co.th\/wetalk\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2b95b7349d23f2efc89b243b406187035f772e87867edf3bb4398abc87dcc097?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b95b7349d23f2efc89b243b406187035f772e87867edf3bb4398abc87dcc097?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cmc.co.th\/wetalk"],"url":"https:\/\/www.cmc.co.th\/wetalk\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cmc.co.th\/wetalk\/wp-content\/uploads\/2025\/06\/yoga-18-scaled.webp","_links":{"self":[{"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/posts\/8380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/comments?post=8380"}],"version-history":[{"count":5,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/posts\/8380\/revisions"}],"predecessor-version":[{"id":8397,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/posts\/8380\/revisions\/8397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/media\/8375"}],"wp:attachment":[{"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/media?parent=8380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/categories?post=8380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmc.co.th\/wetalk\/wp-json\/wp\/v2\/tags?post=8380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}